{"id":13078,"date":"2021-03-27T11:40:46","date_gmt":"2021-03-27T09:40:46","guid":{"rendered":"https:\/\/eugenchocolate.com\/korporativni-pokloni\/moonlight-collection\/"},"modified":"2024-02-02T11:50:15","modified_gmt":"2024-02-02T09:50:15","slug":"moonlight-collection","status":"publish","type":"portfolio","link":"https:\/\/eugenchocolate.com\/en\/corporate-gifts\/moonlight-collection\/","title":{"rendered":"Moonlight Collection"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"13078\" class=\"elementor elementor-13078 elementor-9905\">\n\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-0556ea1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0556ea1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-df4cccc\" data-id=\"df4cccc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e3d23f elementor-widget elementor-widget-wd_image_hotspot\" data-id=\"5e3d23f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_image_hotspot.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-spots wd-event-hover hotspot-icon-default color-scheme- wd-hotspot-static\">\n\t\t\t<div class=\"wd-image-hotspot-hotspots\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-001.jpg\" class=\"wd-image-hotspot-img\" alt=\"Moonlight Collection 01\" srcset=\"https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-001.jpg 1200w, https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-001-300x300.jpg 300w, https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-001-150x150.jpg 150w, https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-001-768x768.jpg 768w, https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-001-600x600.jpg 600w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-image-hotspot hotspot-type-text elementor-repeater-item-23c132f\">\n\t\t\t\t\t\t<span class=\"hotspot-sonar\"><\/span>\n\t\t\t\t\t\t<div class=\"hotspot-btn wd-role-btn wd-fill\" tabindex=\"0\"><\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hotspot-text hotspot-content hotspot-dropdown-top\">\n\t\t\t\t\t\t\t\t<div class=\"hotspot-content-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<h4 class=\"wd-entities-title\">\n\t\t\t\t\t\t\t\t\tLogo\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"hotspot-content-text reset-last-child\">\n\t\t\t\t\t\t\t\t\tEngraved logo on the plate. Plate available in silver or gold color.\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"btn btn-accent\" >\n\t\t\t\t\t\t\t\t\t\tPo\u0161aljite upit\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-image-hotspot hotspot-type-text elementor-repeater-item-64d8e0d\">\n\t\t\t\t\t\t<span class=\"hotspot-sonar\"><\/span>\n\t\t\t\t\t\t<div class=\"hotspot-btn wd-role-btn wd-fill\" tabindex=\"0\"><\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hotspot-text hotspot-content hotspot-dropdown-left\">\n\t\t\t\t\t\t\t\t<div class=\"hotspot-content-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<h4 class=\"wd-entities-title\">\n\t\t\t\t\t\t\t\t\tSatin Bow\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"hotspot-content-text reset-last-child\">\n\t\t\t\t\t\t\t\t\tPossibility to choose the color of the satin bow.\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"btn btn-accent\" >\n\t\t\t\t\t\t\t\t\t\tPo\u0161aljite upit\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-image-hotspot hotspot-type-text elementor-repeater-item-25e9e4c\">\n\t\t\t\t\t\t<span class=\"hotspot-sonar\"><\/span>\n\t\t\t\t\t\t<div class=\"hotspot-btn wd-role-btn wd-fill\" tabindex=\"0\"><\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hotspot-text hotspot-content hotspot-dropdown-top\">\n\t\t\t\t\t\t\t\t<div class=\"hotspot-content-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<h4 class=\"wd-entities-title\">\n\t\t\t\t\t\t\t\t\tBrendirani omoti \u010dokolada\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"hotspot-content-text reset-last-child\">\n\t\t\t\t\t\t\t\t\t1. Printed in full color, or ...\n2. Logo printed with hot stamping technique on tinted covers in the following colors: black, white, blue, green, red, gold or silver.\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"btn btn-accent\"  href=\"#\">\n\t\t\t\t\t\t\t\t\t\tPo\u0161aljite upit\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-73a04f8\" data-id=\"73a04f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3907dcf elementor-widget elementor-widget-heading\" data-id=\"3907dcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Moonlight collection<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dbea42 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"5dbea42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The packaging is made from rigid cardboard which is coated with a special material of attractive texture. The logo is engraved on the gold oval plate on the lid of the box. The box is tied with a golden satin bow. Chocolate wrappers can be customized either in full color or the logo can be printed using the hot stamping technique on tinted paper wrappers.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-cffcc35 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cffcc35\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3987f75\" data-id=\"3987f75\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3baa6d9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3baa6d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Net Weight:<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7a1f18f\" data-id=\"7a1f18f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-228bfcc color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"228bfcc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">140 g (14 x 10 g)<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-13b0009 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"13b0009\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-bc1ef71 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bc1ef71\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f65df8b\" data-id=\"f65df8b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a41573d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a41573d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Box Size:<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ca18d53\" data-id=\"ca18d53\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c4a8135 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"c4a8135\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">170 mm x 70 mm x 50 mm<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-c642759 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c642759\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-92727f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"92727f2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7503604\" data-id=\"7503604\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6387690 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6387690\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Shelf Life:<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-235d6e6\" data-id=\"235d6e6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c27229 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"0c27229\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">12 months<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-df1845e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"df1845e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-6b61c0c elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6b61c0c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-40 elementor-inner-column elementor-element elementor-element-acd3fb0\" data-id=\"acd3fb0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dab4ac3 elementor-widget elementor-widget-wd_popup\" data-id=\"dab4ac3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_popup.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-left\" >\n\t\t\t<a class=\"btn btn-style-default btn-shape-rectangle btn-size-default wd-open-popup btn-color-black btn-icon-pos-right\"  href=\"#contact-form-popup\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tSEND INQUIRY\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"contact-form-popup\" class=\"mfp-hide wd-popup wd-popup-element wd-deferred wd-scroll-content wd-entry-content\" style=\"--wd-popup-width:800px;\">\n\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"12689\" class=\"elementor elementor-12689 elementor-9995 elementor-9995\">\n\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-edc6643 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"edc6643\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b85376\" data-id=\"3b85376\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c62a7a2 wd-cf7 elementor-widget elementor-widget-wd_contact_form_7\" data-id=\"c62a7a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_contact_form_7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f12670-o1\" lang=\"sr-RS\" dir=\"ltr\" data-wpcf7-id=\"12670\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/portfolio\/13078#wpcf7-f12670-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"12670\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"sr_RS\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f12670-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.6\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Your name<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Your e-mail<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Phone number<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-767\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-767\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Company<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"text-1\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"text-1\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<p>Select corporate gift (field required)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-browser\"><span class=\"wpcf7-form-control wpcf7-checkbox wpcf7-validates-as-required\"><span class=\"wpcf7-list-item first\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Chocolate Waltz\" \/><span class=\"wpcf7-list-item-label\">Chocolate Waltz<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Chocolate Purse\" \/><span class=\"wpcf7-list-item-label\">Chocolate Purse<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Chocolate Selection Gift Box - Special Edition\" \/><span class=\"wpcf7-list-item-label\">Chocolate Selection Gift Box - Special Edition<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Chocolate Harmony\" \/><span class=\"wpcf7-list-item-label\">Chocolate Harmony<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Chocolate Harmony Lux\" \/><span class=\"wpcf7-list-item-label\">Chocolate Harmony Lux<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Chocolate Tube\" \/><span class=\"wpcf7-list-item-label\">Chocolate Tube<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Moonlight Collection\" \/><span class=\"wpcf7-list-item-label\">Moonlight Collection<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Mini Choco Tube\" \/><span class=\"wpcf7-list-item-label\">Mini Choco Tube<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Caramel Rhapsody\" \/><span class=\"wpcf7-list-item-label\">Caramel Rhapsody<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Royal Collection - Black Edition\" \/><span class=\"wpcf7-list-item-label\">Royal Collection - Black Edition<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Royal Collection - White Edition\" \/><span class=\"wpcf7-list-item-label\">Royal Collection - White Edition<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Chocolate Perfection 210g\" \/><span class=\"wpcf7-list-item-label\">Chocolate Perfection 210g<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Chocolate Perfection 160g\" \/><span class=\"wpcf7-list-item-label\">Chocolate Perfection 160g<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Chocolate Advent Calendar\" \/><span class=\"wpcf7-list-item-label\">Chocolate Advent Calendar<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Fruit &amp; Chocolate\" \/><span class=\"wpcf7-list-item-label\">Fruit &amp; Chocolate<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Fruit &amp; Chocolate Gift Box\" \/><span class=\"wpcf7-list-item-label\">Fruit &amp; Chocolate Gift Box<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Golden Collection\" \/><span class=\"wpcf7-list-item-label\">Golden Collection<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Chocolate Cubes\" \/><span class=\"wpcf7-list-item-label\">Chocolate Cubes<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Chocolate Selection\" \/><span class=\"wpcf7-list-item-label\">Chocolate Selection<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Chocolate Selection Gift Box\" \/><span class=\"wpcf7-list-item-label\">Chocolate Selection Gift Box<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Choco Pyramid\" \/><span class=\"wpcf7-list-item-label\">Choco Pyramid<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Mini Choco Packet\" \/><span class=\"wpcf7-list-item-label\">Mini Choco Packet<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Choco letter\" \/><span class=\"wpcf7-list-item-label\">Choco letter<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Single Chocolate 10g\" \/><span class=\"wpcf7-list-item-label\">Single Chocolate 10g<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Golden Symphony\" \/><span class=\"wpcf7-list-item-label\">Golden Symphony<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Golden Sonata - No Sugar\" \/><span class=\"wpcf7-list-item-label\">Golden Sonata - No Sugar<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Mini Tube Gift Box\" \/><span class=\"wpcf7-list-item-label\">Mini Tube Gift Box<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Lady Perfection\" \/><span class=\"wpcf7-list-item-label\">Lady Perfection<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Lady Symphony\" \/><span class=\"wpcf7-list-item-label\">Lady Symphony<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Lady Symphony\" \/><span class=\"wpcf7-list-item-label\">Lady Symphony<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Lady Perfction\" \/><span class=\"wpcf7-list-item-label\">Lady Perfction<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Lady Premium\" \/><span class=\"wpcf7-list-item-label\">Lady Premium<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Lady Mind &amp; Heart\" \/><span class=\"wpcf7-list-item-label\">Lady Mind &amp; Heart<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Lady Sonata\" \/><span class=\"wpcf7-list-item-label\">Lady Sonata<\/span><\/span><span class=\"wpcf7-list-item last\"><input type=\"checkbox\" name=\"your-browser[]\" value=\"Fabulous Box\" \/><span class=\"wpcf7-list-item-label\">Fabulous Box<\/span><\/span><\/span><\/span>\n<\/p>\n<p><label>Your message<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn-color-black\" type=\"submit\" value=\"SEND\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-60 elementor-top-column elementor-element elementor-element-d501594\" data-id=\"d501594\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-00e33c1 e-grid-align-right elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"00e33c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-7cc16ce\" href=\"https:\/\/www.facebook.com\/Eugen-Chocolate-148376955206345\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-b722d20\" href=\"https:\/\/twitter.com\/EugenChocolate\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-102665b\" href=\"https:\/\/www.youtube.com\/channel\/UCn5LHfsIAmD0i9CIEvExonQ\/videos\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-135b11b\" href=\"https:\/\/www.instagram.com\/eugen_chocolate\/?hl=en\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-9f467fb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f467fb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-caa24af\" data-id=\"caa24af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d374a1 elementor-widget elementor-widget-image\" data-id=\"5d374a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-003.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"OPT Moonlight Collection 003\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTM5MjIsInVybCI6Imh0dHBzOlwvXC9ldWdlbmNob2NvbGF0ZS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzAzXC9PUFQtTW9vbmxpZ2h0LUNvbGxlY3Rpb24tMDAzLmpwZyJ9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-003.jpg\" class=\"attachment-large size-large wp-image-13922\" alt=\"\" srcset=\"https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-003.jpg 1200w, https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-003-300x300.jpg 300w, https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-003-150x150.jpg 150w, https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-003-768x768.jpg 768w, https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-003-600x600.jpg 600w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-61cd81e\" data-id=\"61cd81e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b6a5ce elementor-widget elementor-widget-image\" data-id=\"4b6a5ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-002.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"OPT Moonlight Collection 002\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTM5MjAsInVybCI6Imh0dHBzOlwvXC9ldWdlbmNob2NvbGF0ZS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzAzXC9PUFQtTW9vbmxpZ2h0LUNvbGxlY3Rpb24tMDAyLmpwZyJ9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-002.jpg\" class=\"attachment-large size-large wp-image-13920\" alt=\"\" srcset=\"https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-002.jpg 1200w, https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-002-300x300.jpg 300w, https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-002-150x150.jpg 150w, https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-002-768x768.jpg 768w, https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-002-600x600.jpg 600w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Logo Engraved logo on the plate. Plate available in silver or gold color. Po\u0161aljite upit Satin Bow Possibility to choose<\/p>\n","protected":false},"featured_media":13918,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","project-cat":[157,201],"class_list":["post-13078","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","project-cat-luxury-boxes","project-cat-middle-range"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Moonlight Collection - Corporate gift - Eugen Chocolate<\/title>\n<meta name=\"description\" content=\"The packaging is made of hard cardboard which is coated with a special material of attractive texture. Net weight: 140g (14 x 10g).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eugenchocolate.com\/en\/corporate-gifts\/moonlight-collection\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Moonlight Collection - Corporate gift - Eugen Chocolate\" \/>\n<meta property=\"og:description\" content=\"The packaging is made of hard cardboard which is coated with a special material of attractive texture. Net weight: 140g (14 x 10g).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eugenchocolate.com\/en\/corporate-gifts\/moonlight-collection\/\" \/>\n<meta property=\"og:site_name\" content=\"Eugen Chocolate\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eugenchocolate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-02T09:50:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eugenchocolate.com\\\/en\\\/corporate-gifts\\\/moonlight-collection\\\/\",\"url\":\"https:\\\/\\\/eugenchocolate.com\\\/en\\\/corporate-gifts\\\/moonlight-collection\\\/\",\"name\":\"Moonlight Collection - Corporate gift - Eugen Chocolate\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eugenchocolate.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eugenchocolate.com\\\/en\\\/corporate-gifts\\\/moonlight-collection\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eugenchocolate.com\\\/en\\\/corporate-gifts\\\/moonlight-collection\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eugenchocolate.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/OPT-Moonlight-Collection-001.jpg\",\"datePublished\":\"2021-03-27T09:40:46+00:00\",\"dateModified\":\"2024-02-02T09:50:15+00:00\",\"description\":\"The packaging is made of hard cardboard which is coated with a special material of attractive texture. Net weight: 140g (14 x 10g).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eugenchocolate.com\\\/en\\\/corporate-gifts\\\/moonlight-collection\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eugenchocolate.com\\\/en\\\/corporate-gifts\\\/moonlight-collection\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eugenchocolate.com\\\/en\\\/corporate-gifts\\\/moonlight-collection\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eugenchocolate.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/OPT-Moonlight-Collection-001.jpg\",\"contentUrl\":\"https:\\\/\\\/eugenchocolate.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/OPT-Moonlight-Collection-001.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"Moonlight Collection 01\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eugenchocolate.com\\\/en\\\/corporate-gifts\\\/moonlight-collection\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Po\u010detna\",\"item\":\"https:\\\/\\\/eugenchocolate.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\\\/\\\/eugenchocolate.com\\\/en\\\/corporate-gifts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chocolate\",\"item\":\"https:\\\/\\\/eugenchocolate.com\\\/en\\\/gifts\\\/chocolate\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Moonlight Collection\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eugenchocolate.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/eugenchocolate.com\\\/en\\\/\",\"name\":\"Eugen Chocolate\",\"description\":\"The finest handcrafted chocolates\",\"publisher\":{\"@id\":\"https:\\\/\\\/eugenchocolate.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eugenchocolate.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eugenchocolate.com\\\/en\\\/#organization\",\"name\":\"Eugen Chocolate\",\"url\":\"https:\\\/\\\/eugenchocolate.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eugenchocolate.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eugenchocolate.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Eugen-logo.png\",\"contentUrl\":\"https:\\\/\\\/eugenchocolate.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Eugen-logo.png\",\"width\":105,\"height\":105,\"caption\":\"Eugen Chocolate\"},\"image\":{\"@id\":\"https:\\\/\\\/eugenchocolate.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eugenchocolate\\\/\",\"https:\\\/\\\/www.instagram.com\\\/eugen_chocolate\\\/?hl=en\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCn5LHfsIAmD0i9CIEvExonQ\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Moonlight Collection - Corporate gift - Eugen Chocolate","description":"The packaging is made of hard cardboard which is coated with a special material of attractive texture. Net weight: 140g (14 x 10g).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eugenchocolate.com\/en\/corporate-gifts\/moonlight-collection\/","og_locale":"en_US","og_type":"article","og_title":"Moonlight Collection - Corporate gift - Eugen Chocolate","og_description":"The packaging is made of hard cardboard which is coated with a special material of attractive texture. Net weight: 140g (14 x 10g).","og_url":"https:\/\/eugenchocolate.com\/en\/corporate-gifts\/moonlight-collection\/","og_site_name":"Eugen Chocolate","article_publisher":"https:\/\/www.facebook.com\/eugenchocolate\/","article_modified_time":"2024-02-02T09:50:15+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-001.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eugenchocolate.com\/en\/corporate-gifts\/moonlight-collection\/","url":"https:\/\/eugenchocolate.com\/en\/corporate-gifts\/moonlight-collection\/","name":"Moonlight Collection - Corporate gift - Eugen Chocolate","isPartOf":{"@id":"https:\/\/eugenchocolate.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eugenchocolate.com\/en\/corporate-gifts\/moonlight-collection\/#primaryimage"},"image":{"@id":"https:\/\/eugenchocolate.com\/en\/corporate-gifts\/moonlight-collection\/#primaryimage"},"thumbnailUrl":"https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-001.jpg","datePublished":"2021-03-27T09:40:46+00:00","dateModified":"2024-02-02T09:50:15+00:00","description":"The packaging is made of hard cardboard which is coated with a special material of attractive texture. Net weight: 140g (14 x 10g).","breadcrumb":{"@id":"https:\/\/eugenchocolate.com\/en\/corporate-gifts\/moonlight-collection\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eugenchocolate.com\/en\/corporate-gifts\/moonlight-collection\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eugenchocolate.com\/en\/corporate-gifts\/moonlight-collection\/#primaryimage","url":"https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-001.jpg","contentUrl":"https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/OPT-Moonlight-Collection-001.jpg","width":1200,"height":1200,"caption":"Moonlight Collection 01"},{"@type":"BreadcrumbList","@id":"https:\/\/eugenchocolate.com\/en\/corporate-gifts\/moonlight-collection\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Po\u010detna","item":"https:\/\/eugenchocolate.com\/en\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/eugenchocolate.com\/en\/corporate-gifts\/"},{"@type":"ListItem","position":3,"name":"Chocolate","item":"https:\/\/eugenchocolate.com\/en\/gifts\/chocolate\/"},{"@type":"ListItem","position":4,"name":"Moonlight Collection"}]},{"@type":"WebSite","@id":"https:\/\/eugenchocolate.com\/en\/#website","url":"https:\/\/eugenchocolate.com\/en\/","name":"Eugen Chocolate","description":"The finest handcrafted chocolates","publisher":{"@id":"https:\/\/eugenchocolate.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eugenchocolate.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/eugenchocolate.com\/en\/#organization","name":"Eugen Chocolate","url":"https:\/\/eugenchocolate.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eugenchocolate.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/Eugen-logo.png","contentUrl":"https:\/\/eugenchocolate.com\/wp-content\/uploads\/2021\/03\/Eugen-logo.png","width":105,"height":105,"caption":"Eugen Chocolate"},"image":{"@id":"https:\/\/eugenchocolate.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eugenchocolate\/","https:\/\/www.instagram.com\/eugen_chocolate\/?hl=en","https:\/\/www.youtube.com\/channel\/UCn5LHfsIAmD0i9CIEvExonQ\/videos"]}]}},"_links":{"self":[{"href":"https:\/\/eugenchocolate.com\/en\/wp-json\/wp\/v2\/portfolio\/13078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eugenchocolate.com\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/eugenchocolate.com\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/eugenchocolate.com\/en\/wp-json\/wp\/v2\/comments?post=13078"}],"version-history":[{"count":23,"href":"https:\/\/eugenchocolate.com\/en\/wp-json\/wp\/v2\/portfolio\/13078\/revisions"}],"predecessor-version":[{"id":25072,"href":"https:\/\/eugenchocolate.com\/en\/wp-json\/wp\/v2\/portfolio\/13078\/revisions\/25072"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eugenchocolate.com\/en\/wp-json\/wp\/v2\/media\/13918"}],"wp:attachment":[{"href":"https:\/\/eugenchocolate.com\/en\/wp-json\/wp\/v2\/media?parent=13078"}],"wp:term":[{"taxonomy":"project-cat","embeddable":true,"href":"https:\/\/eugenchocolate.com\/en\/wp-json\/wp\/v2\/project-cat?post=13078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}